{"id":47210,"count":1,"description":"","link":"https:\/\/site.itshrt.com\/news\/tag\/bridge-swept-away\/","name":"bridge swept away","slug":"bridge-swept-away","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>bridge swept away Archives - News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/site.itshrt.com\/news\/tag\/bridge-swept-away\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"bridge swept away Archives - News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/site.itshrt.com\/news\/tag\/bridge-swept-away\/\" \/>\n<meta property=\"og:site_name\" content=\"News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/site.itshrt.com\/news\/tag\/bridge-swept-away\/\",\"url\":\"https:\/\/site.itshrt.com\/news\/tag\/bridge-swept-away\/\",\"name\":\"bridge swept away Archives - News\",\"isPartOf\":{\"@id\":\"https:\/\/site.itshrt.com\/news\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/site.itshrt.com\/news\/tag\/bridge-swept-away\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/site.itshrt.com\/news\/tag\/bridge-swept-away\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/site.itshrt.com\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"bridge swept away\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/site.itshrt.com\/news\/#website\",\"url\":\"https:\/\/site.itshrt.com\/news\/\",\"name\":\"News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/site.itshrt.com\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"bridge swept away Archives - News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/site.itshrt.com\/news\/tag\/bridge-swept-away\/","og_locale":"en_US","og_type":"article","og_title":"bridge swept away Archives - News","og_url":"https:\/\/site.itshrt.com\/news\/tag\/bridge-swept-away\/","og_site_name":"News","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/site.itshrt.com\/news\/tag\/bridge-swept-away\/","url":"https:\/\/site.itshrt.com\/news\/tag\/bridge-swept-away\/","name":"bridge swept away Archives - News","isPartOf":{"@id":"https:\/\/site.itshrt.com\/news\/#website"},"breadcrumb":{"@id":"https:\/\/site.itshrt.com\/news\/tag\/bridge-swept-away\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/site.itshrt.com\/news\/tag\/bridge-swept-away\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/site.itshrt.com\/news\/"},{"@type":"ListItem","position":2,"name":"bridge swept away"}]},{"@type":"WebSite","@id":"https:\/\/site.itshrt.com\/news\/#website","url":"https:\/\/site.itshrt.com\/news\/","name":"News","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/site.itshrt.com\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/site.itshrt.com\/news\/wp-json\/wp\/v2\/tags\/47210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.itshrt.com\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/site.itshrt.com\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/site.itshrt.com\/news\/wp-json\/wp\/v2\/posts?tags=47210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}