{"id":30558,"count":1,"description":"","link":"https:\/\/site.itshrt.com\/gaming\/tag\/horror-game-challenge\/","name":"horror game challenge","slug":"horror-game-challenge","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>horror game challenge Archives - Gaming Source<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/site.itshrt.com\/gaming\/tag\/horror-game-challenge\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"horror game challenge Archives - Gaming Source\" \/>\n<meta property=\"og:url\" content=\"https:\/\/site.itshrt.com\/gaming\/tag\/horror-game-challenge\/\" \/>\n<meta property=\"og:site_name\" content=\"Gaming Source\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/site.itshrt.com\/gaming\/tag\/horror-game-challenge\/\",\"url\":\"https:\/\/site.itshrt.com\/gaming\/tag\/horror-game-challenge\/\",\"name\":\"horror game challenge Archives - Gaming Source\",\"isPartOf\":{\"@id\":\"https:\/\/site.itshrt.com\/gaming\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/site.itshrt.com\/gaming\/tag\/horror-game-challenge\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/site.itshrt.com\/gaming\/tag\/horror-game-challenge\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/site.itshrt.com\/gaming\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"horror game challenge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/site.itshrt.com\/gaming\/#website\",\"url\":\"https:\/\/site.itshrt.com\/gaming\/\",\"name\":\"Gaming Source\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/site.itshrt.com\/gaming\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"horror game challenge Archives - Gaming Source","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/site.itshrt.com\/gaming\/tag\/horror-game-challenge\/","og_locale":"en_US","og_type":"article","og_title":"horror game challenge Archives - Gaming Source","og_url":"https:\/\/site.itshrt.com\/gaming\/tag\/horror-game-challenge\/","og_site_name":"Gaming Source","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/site.itshrt.com\/gaming\/tag\/horror-game-challenge\/","url":"https:\/\/site.itshrt.com\/gaming\/tag\/horror-game-challenge\/","name":"horror game challenge Archives - Gaming Source","isPartOf":{"@id":"https:\/\/site.itshrt.com\/gaming\/#website"},"breadcrumb":{"@id":"https:\/\/site.itshrt.com\/gaming\/tag\/horror-game-challenge\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/site.itshrt.com\/gaming\/tag\/horror-game-challenge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/site.itshrt.com\/gaming\/"},{"@type":"ListItem","position":2,"name":"horror game challenge"}]},{"@type":"WebSite","@id":"https:\/\/site.itshrt.com\/gaming\/#website","url":"https:\/\/site.itshrt.com\/gaming\/","name":"Gaming Source","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/site.itshrt.com\/gaming\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/site.itshrt.com\/gaming\/wp-json\/wp\/v2\/tags\/30558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.itshrt.com\/gaming\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/site.itshrt.com\/gaming\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/site.itshrt.com\/gaming\/wp-json\/wp\/v2\/posts?tags=30558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}